{"id":30433,"date":"2026-03-24T09:53:01","date_gmt":"2026-03-24T00:53:01","guid":{"rendered":"https:\/\/game.technophere.com\/brawlstars\/satomi-springs-api\/"},"modified":"2026-03-24T09:53:01","modified_gmt":"2026-03-24T00:53:01","slug":"satomi-springs-api","status":"publish","type":"post","link":"https:\/\/game.technophere.com\/brawlstars\/satomi-springs-api\/","title":{"rendered":"\u3010\u30d6\u30ed\u30b9\u30bf\u3011\u30b5\u30c8\u30df\u306e\u6cc9\u306e\u9069\u6b63\u30ad\u30e3\u30e9\u30fb\u52dd\u7387\u30fb\u4f7f\u7528\u7387\uff5c\u30a8\u30e1\u30e9\u30eb\u30c9\u30cf\u30f3\u30c8"},"content":{"rendered":"    <div class=\"bstl-map-detail\">\n        <div class=\"bstl-map-detail-header\">\n            <div class=\"bstl-map-detail-img\">\n                <img decoding=\"async\" src=\"https:\/\/cdn.brawlify.com\/maps\/regular\/15001209.png\" alt=\"Satomi Springs\" \/>\n            <\/div>\n            <div class=\"bstl-map-detail-info\">\n                <h3>\u30de\u30c3\u30d7\u60c5\u5831<\/h3>\n                <dl>\n                    <dt>\u30b2\u30fc\u30e0\u30e2\u30fc\u30c9<\/dt>\n                    <dd>\u30a8\u30e1\u30e9\u30eb\u30c9\u30cf\u30f3\u30c8<\/dd>\n                                            <dt>\u4f5c\u8005<\/dt>\n                        <dd>Zappy Hype<\/dd>\n                                                                <dt>\u74b0\u5883<\/dt>\n                        <dd>Mortuary<\/dd>\n                                        <dt>\u72b6\u614b<\/dt>\n                    <dd><span class=\"bstl-status-active\">\u6709\u52b9<\/span><\/dd>\n                                    <\/dl>\n            <\/div>\n        <\/div>\n\n        <div class=\"bstl-map-vote-section\" data-map-name=\"Satomi Springs\">\n            <div class=\"bstl-vote-block\" data-vote-type=\"character\">\n                <h4>\u304a\u3059\u3059\u3081\u30ad\u30e3\u30e9\u6295\u7968<\/h4>\n                <div class=\"bstl-vote-cells character-votes\">\n                    <div class=\"bstl-vote-cell-plus\" data-index=\"0\" title=\"\u30ad\u30e3\u30e9\u3092\u9078\u629e\u3057\u3066\u6295\u7968\">+<\/div>\n                    <button class=\"bstl-char-vote-submit\" disabled>\u3053\u306e\u30ad\u30e3\u30e9\u3067\u6295\u7968<\/button>\n                <\/div>\n            <\/div>\n\n            <div class=\"bstl-vote-block\" data-vote-type=\"composition\">\n                <h4>\u304a\u3059\u3059\u3081\u7de8\u6210\u6295\u7968<\/h4>\n                <div class=\"bstl-vote-cells composition-votes\">\n                    <div class=\"bstl-vote-cell-plus\" data-index=\"0\" title=\"\u30ad\u30e3\u30e91\u3092\u9078\u629e\">+<\/div>\n                    <div class=\"bstl-vote-cell-plus\" data-index=\"1\" title=\"\u30ad\u30e3\u30e92\u3092\u9078\u629e\">+<\/div>\n                    <div class=\"bstl-vote-cell-plus\" data-index=\"2\" title=\"\u30ad\u30e3\u30e93\u3092\u9078\u629e\">+<\/div>\n                    <button class=\"bstl-comp-vote-submit\" disabled>\u3053\u306e\u7de8\u6210\u3067\u6295\u7968<\/button>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        <div class=\"bstl-map-vote-results-section\">\n            <h3 class=\"bstl-section-title\">\u304a\u3059\u3059\u3081\u30ad\u30e3\u30e9\uff08\u30e6\u30fc\u30b6\u30fc\u6295\u7968\uff09<\/h3>\n            <div class=\"bstl-vote-results character-results\">\n                <!-- \u6295\u7968\u7d50\u679c\u304c\u3053\u3053\u306b\u8868\u793a\u3055\u308c\u308b -->\n            <\/div>\n        <\/div>\n\n        <div class=\"bstl-map-vote-results-section\">\n            <h3 class=\"bstl-section-title\">\u304a\u3059\u3059\u3081\u7de8\u6210\uff08\u30e6\u30fc\u30b6\u30fc\u6295\u7968\uff09<\/h3>\n            <div class=\"bstl-vote-results composition-results\">\n                <!-- \u6295\u7968\u7d50\u679c\u304c\u3053\u3053\u306b\u8868\u793a\u3055\u308c\u308b -->\n            <\/div>\n        <\/div>\n\n        <div class=\"bstl-map-stats-section\">\n            <h3 class=\"bstl-section-title\">\u30ad\u30e3\u30e9\u30af\u30bf\u30fc\u5225\u7d71\u8a08\uff08\u52dd\u7387\u9806\uff09<\/h3>\n                            <p class=\"bstl-no-stats\">\u73fe\u5728\u5229\u7528\u53ef\u80fd\u306a\u7d71\u8a08\u30c7\u30fc\u30bf\u306f\u3042\u308a\u307e\u305b\u3093\u3002<\/p>\n                    <\/div>\n    <\/div>\n    <style>\n        .bstl-map-detail-header {\n            display: flex;\n            gap: 20px;\n            margin-bottom: 30px;\n            flex-wrap: wrap;\n        }\n\n        .bstl-map-detail-img {\n            flex: 0 1 300px;\n            max-width: 300px;\n            width: 100%;\n            margin: 0;\n        }\n\n        @media (max-width: 600px) {\n            .bstl-map-detail-img {\n                margin: 0 auto 20px auto;\n                flex: 0 1 auto;\n                \/* \u30b9\u30de\u30db\u3067\u306f\u30b3\u30f3\u30c6\u30f3\u30c4\u306b\u5408\u308f\u305b\u3066\u7e2e\u5c0f\u53ef\u80fd\u306b *\/\n            }\n        }\n\n        .bstl-map-detail-img img {\n            width: 100%;\n            height: auto;\n            border-radius: 8px;\n            box-shadow: 0 4px 10px rgba(0, 0, 0, 0.1);\n            display: block;\n        }\n\n        .bstl-map-detail-info {\n            flex: 1;\n            min-width: 300px;\n        }\n\n        .bstl-map-detail-info dl {\n            display: grid;\n            grid-template-columns: auto 1fr;\n            gap: 10px 20px;\n            margin: 0;\n            background: #fff;\n            padding: 20px;\n            border-radius: 8px;\n            border: 1px solid #eee;\n            width: 100%;\n        }\n\n        .bstl-map-detail-info dt {\n            font-weight: bold;\n            color: #666;\n            margin: 0;\n        }\n\n        .bstl-map-detail-info dd {\n            margin: 0;\n            color: #333;\n        }\n\n        .bstl-status-active {\n            color: #2ed573;\n            font-weight: bold;\n        }\n\n        .bstl-status-disabled {\n            color: #ff4757;\n            font-weight: bold;\n        }\n\n        .bstl-map-vote-results-section {\n            margin-top: 30px;\n            margin-bottom: 50px;\n        }\n\n        .bstl-map-stats-section {\n            margin-top: 30px;\n        }\n    <\/style>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"swell_btn_cv_data":"","_locale":"ja","_original_post":"https:\/\/game.technophere.com\/brawlstars\/satomi-springs-api\/","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[167],"tags":[351,1391],"class_list":["post-30433","post","type-post","status-publish","format-standard","hentry","category-167","tag-351","tag-1391","ja"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/game.technophere.com\/brawlstars\/wp-json\/wp\/v2\/posts\/30433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/game.technophere.com\/brawlstars\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/game.technophere.com\/brawlstars\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/game.technophere.com\/brawlstars\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/game.technophere.com\/brawlstars\/wp-json\/wp\/v2\/comments?post=30433"}],"version-history":[{"count":0,"href":"https:\/\/game.technophere.com\/brawlstars\/wp-json\/wp\/v2\/posts\/30433\/revisions"}],"wp:attachment":[{"href":"https:\/\/game.technophere.com\/brawlstars\/wp-json\/wp\/v2\/media?parent=30433"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/game.technophere.com\/brawlstars\/wp-json\/wp\/v2\/categories?post=30433"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/game.technophere.com\/brawlstars\/wp-json\/wp\/v2\/tags?post=30433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}